{"id":917,"date":"2010-11-02T00:32:30","date_gmt":"2010-11-02T04:32:30","guid":{"rendered":"http:\/\/blogviejo.sld.cu\/avisosciclon\/?p=917"},"modified":"2010-11-02T00:32:30","modified_gmt":"2010-11-02T04:32:30","slug":"tormenta-tropical-tomas-aviso-no-13","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/behique\/2010\/11\/02\/tormenta-tropical-tomas-aviso-no-13\/","title":{"rendered":"Tormenta tropical Tomas Aviso No. 13"},"content":{"rendered":"<p>Aviso de Cicl\u00f3n Tropical.<br \/>\nCentro de Pron\u00f3sticos, INSMET.<br \/>\nFecha: 1ro de Noviembre de 2010 Hora: 6:00 PM.<\/p>\n<p>AVISO DE CICLON TROPICAL No 13.<\/p>\n<p>TORMENTA TROPICAL TOM\u00c1S.<\/p>\n<p>&#8230; Tom\u00e1s desorganizada sobre el Mar Caribe central&#8230;<\/p>\n<p>Durante la tarde la tormenta tropical Tom\u00e1s se ha mantenido con poco cambio en intensidad, algo m\u00e1s desorganizada. Sus vientos m\u00e1ximos sostenidos siguen siendo de 75 kil\u00f3metros por hora, con rachas superiores y su presi\u00f3n m\u00ednima central es de 1005 hectoPascal. Se est\u00e1 desplazando en un rumbo pr\u00f3ximo al Oeste a 19 kil\u00f3metros por hora.<\/p>\n<p>A las seis de la tarde su regi\u00f3n central se estim\u00f3 en los 13.4 grados de latitud Norte y los 70.1 grados de longitud Oeste, posici\u00f3n que la sit\u00faa a 100 kil\u00f3metros al Norte de Aruba, Antillas Holandesas y a unos 625 kil\u00f3metros al Sur Sudeste de Puerto Pr\u00edncipe, Hait\u00ed.<\/p>\n<p>Se pronostica que en las pr\u00f3ximas 24 a 48 horas esta tormenta tropical se mantendr\u00e1 con poco cambio en intensidad, fortaleci\u00e9ndose a partir del mi\u00e9rcoles. Tom\u00e1s debe mantener igual rumbo, disminuyendo algo su velocidad de traslaci\u00f3n.<\/p>\n<p>El pr\u00f3ximo aviso de cicl\u00f3n tropical se emitir\u00e1 a la medianoche del martes.<\/p>\n<p>Y. Cede\u00f1o\u00a0 J. Palacios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aviso de Cicl\u00f3n Tropical. Centro de Pron\u00f3sticos, INSMET. Fecha: 1ro de Noviembre de 2010 Hora: 6:00 PM. AVISO DE CICLON TROPICAL No 13. TORMENTA TROPICAL TOM\u00c1S. &#8230; Tom\u00e1s desorganizada sobre el Mar Caribe central&#8230; Durante la tarde la tormenta tropical Tom\u00e1s se ha mantenido con poco cambio en intensidad, algo m\u00e1s desorganizada. Sus vientos m\u00e1ximos [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[166,7,11],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/posts\/917"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/comments?post=917"}],"version-history":[{"count":0,"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/posts\/917\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/media?parent=917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/categories?post=917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/behique\/wp-json\/wp\/v2\/tags?post=917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}