{"id":40,"date":"2008-04-15T18:48:41","date_gmt":"2008-04-15T18:48:41","guid":{"rendered":"http:\/\/cibernetica.wordpress.com\/?p=40"},"modified":"2008-04-15T18:48:41","modified_gmt":"2008-04-15T18:48:41","slug":"las-tecnoutopias-y-el-fin-de-la-humanidad","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/cibernetica\/2008\/04\/15\/las-tecnoutopias-y-el-fin-de-la-humanidad\/","title":{"rendered":"Las tecnoutopias y el fin de la humanidad"},"content":{"rendered":"<p>Los escritores de ciencia ficci\u00f3n siempre han tratado el tema del fin del mundo y siempre se ha visto como el mayor peligro que enfrenta la humanidad, tema incluso de la Biblia que anuncia la llegada del anticristo y el fin del mundo, siempre utilizado bajo la \u00f3ptica del terror.<\/p>\n<p>El futuro de los robots siempre ha sido uno de los grandes temas de la ciencia ficci\u00f3n, veremos como los escritores y los tecnofuturistas (aquellos que se dedican al futuro desde un enfoque puramente tecnocient\u00edfico).<\/p>\n<p>Una de las ideas preferidas es, si la criatura se volviera contra su creador: los robots como monstruos fuera de control que siembran el terror. Basado en mitos arquet\u00edpicos: Pigmalion, el aprendiz de brujo. El demiurgo desencadenar\u00e1 poderes diab\u00f3licos que acabaran con \u00e9l.<\/p>\n<p>Como medida para suavizar el terror que inspira el mito de los robots fuera de control. El escritor Isaac Asimov defini\u00f3 las 3 leyes de la rob\u00f3tica:<br \/>\n1) Un robot no debe herir a un ser humano, ni permitir que, por su inacci\u00f3n, le ocurra nada malo.<br \/>\n2) Un robot debe obedecer las \u00f3rdenes que recibe de los seres humanos excepto cuando se oponga a la primera ley.<br \/>\n3) Un robot debe proteger su propia existencia mientras tal protecci\u00f3n no este en pugna con las leyes anteriores.<\/p>\n<p>Otro de los temas se basa en los robots como herederos del hombre por medio de una fusi\u00f3n entre hombres y m\u00e1quinas: hombre prot\u00e9sico, cyborg (parte humano y parte m\u00e1quina) o ya sea por los robot van sustituyendo lentamente a los humanos. De este tema hablaremos mas adelante.<\/p>\n<p>Hasta llegar a los temas m\u00e1s filos\u00f3ficos donde se especula sobre las consecuencias filos\u00f3ficas y morales de los robots, tales como:<br \/>\n&#8211; La dificultad de haber creado robots demasiado perfectos, sus discrepancias, su integraci\u00f3n social.<br \/>\n&#8211; Los hombres crearon robot incapaces de adaptarse y esa incapacidad representa un peligro para el hombre.<br \/>\n&#8211; Los robots no pueden ser lo que los hombres esperan de ellos.<br \/>\n&#8211; Los robots son demasiado perfectos<br \/>\n&#8211; La diferencia entre los robots y los hombres. Sus relaciones, discrepancias. Su integraci\u00f3n social.<\/p>\n<p>De estas ideas de la ciencia ficci\u00f3n se nutrieron los primeros tecnofutursitas en su mayor\u00eda escritores, muchos de ellos dedicados a la ciencia. Los tecnofuturistas est\u00e1n convencidos de que el fin de la humanidad es inevitable y la \u00fanica forma de sobrevivir es por medio de la tecnolog\u00eda, pasaron de la idea de las m\u00e1quinas dominando al planeta a unas m\u00e1quinas que heredan el planeta ante las amenazas del fin del mundo. Para los tecnofuturistas la evoluci\u00f3n de la humanidad es defectuosa e \u201cinsostenible\u201d y es necesario crear un nuevo tipo de evoluci\u00f3n no natural con un crecimiento y desarrollo ilimitado. Como representantes de estas ideas est\u00e1n: Vernor Vingen, Hans Moravec y Rudy Rucker. A este primer grupo seguir\u00eda otro formado por cient\u00edficos de renombre que vendr\u00edan a darle mayor auge a estas ideas como son: Marvin Minsky y Ray Kurzweil.<br \/>\nEs bueno se\u00f1alar desde ahora, para tener una mejor comprensi\u00f3n de estas ideas; y es que los tecnofuturistas no ven el car\u00e1cter \u201cinsostenible\u201d en las desigualdades sociales, en la competencia ni en el consumismo sino en las limitaciones humanas; y que las amenazas no est\u00e1n en las tecnolog\u00edas fuera de control sino en la inteligencia humana fuera de control producto de su actitud ego\u00edsta, sus impulsos destructivos y su af\u00e1n de poder lo que convierte a la tecnolog\u00eda en un arma de destrucci\u00f3n capaz de acabar con la raza humana.<\/p>\n<p>Alimentados de las ideas de los tecnofuturistas, surgen varios movimientos que aspiran a un futuro mejor basados en la tecnolog\u00eda (tecnoutopias), siendo el m\u00e1s representativo el movimiento transhumanista (Ver: \u201cQue es un transhumano\u201d). Los transhumanistas aportan una nueva ideolog\u00eda con matices religiosos en la que prometen alcanzar el para\u00edso en la tierra, en un mundo sin enfermedades, sin envejecer, donde no existe la muerte. Su centro es el individuo y las limitaciones de la condici\u00f3n humana y aspiran por medio de la tecnolog\u00eda a liberar al hombre de sus sufrimientos.<\/p>\n<p>Por \u00faltimo la convergencia de las tecnolog\u00edas nano, bio, info y cogno, las NBIC; el nuevo proyecto Manhatan Norteamericano. (Ver: \u201cQue significa NBIC\u201d) y la nueva tecnoutopia basada en que la tecnolog\u00eda por si sola puede resolver todos los problemas del planeta: contaminaci\u00f3n pobreza, desigualdades\u2026 Esta convergencia, ligereada por la nanotecnologia, llevar\u00e1 la humanidad a un nuevo desarrollo y progresos insospechados y por supuesto afianzara el papel hegem\u00f3nico de los Estados Unidos. Un papel importante en estas concepciones lo ha jugado el movimiento transhumanista con su ideolog\u00eda de lograr un humano mejorado.<\/p>\n<p>Con las tecnolog\u00edas NBIC se cierra el ciclo y la ideas de una tecnoutopia abstracta toma cuerpo y comienza a vislumbrase su materializaci\u00f3n en los pa\u00edses altamente desarrollados.<\/p>\n<p>Recomendaci\u00f3n:<br \/>\n<a title=\"IA el futuro del hombre\" href=\"http:\/\/www.amazon.es\/Inteligencia-Artificial-futuro-hombre-ebook\/dp\/B00CP89UR4\/ref=sr_1_1?s=books&amp;ie=UTF8&amp;qid=1372086572&amp;sr=1-1&amp;keywords=inteligencia+artificial+el+futuro+del+hombre\">Inteligencia Artificial, el futuro del hombre<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los escritores de ciencia ficci\u00f3n siempre han tratado el tema del fin del mundo y siempre se ha visto como el mayor peligro que enfrenta la humanidad, tema incluso de la Biblia que anuncia la llegada del anticristo y el fin del mundo, siempre utilizado bajo la \u00f3ptica del terror. El futuro de los robots [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[20,45,159,261,269],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/posts\/40"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":0,"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/cibernetica\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}