{"id":17893,"date":"2011-11-01T11:55:48","date_gmt":"2011-11-01T15:55:48","guid":{"rendered":"http:\/\/blogviejo.sld.cu\/marionod\/?p=17893"},"modified":"2011-11-01T11:55:48","modified_gmt":"2011-11-01T15:55:48","slug":"farmacoterapia-paliativa-administracion-de-medicamentos","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/marionod\/2011\/11\/01\/farmacoterapia-paliativa-administracion-de-medicamentos\/","title":{"rendered":"Farmacoterapia Paliativa. Administraci\u00f3n de Medicamentos"},"content":{"rendered":"<p><a href=\"http:\/\/www.sovpal.org\/upload\/publica\/cuidados%20paliativos\/Tratamientos%20Paliativos\/FARMACOTERAPIA-PALIATIVA-MEDICACION-07-HERNANZ.pdf\" target=\"_blank\">Farmacoterapia Paliativa. Administraci\u00f3n de Medicamentos<\/a><\/p>\n<p>La <a href=\"http:\/\/www.sovpal.org\/\" target=\"_blank\">Sociedad Vasca de Cuidados Paliativos<\/a> ha publicado este art\u00edculo sobre farmacoterapia paliativa.<\/p>\n<p>Una de las bases sobre la que se sustentan los cuidados paliativos es el control de los s\u00edntomas, que pueden ser m\u00faltiples, cambiantes, de intensidad variable y origen multifactorial. Para una adecuada farmacoterapia ser\u00e1 necesario:<br \/>\n&#8211; Realizar una evaluaci\u00f3n etiol\u00f3gica previa al tratamiento para saber si un s\u00edntoma es atribuible a la enfermedad de base, secundario a otra patolog\u00eda, o al tratamiento que recibe.<br \/>\n&#8211; Determinar la necesidad de tratar un s\u00edntoma en funci\u00f3n de la evoluci\u00f3n y situaci\u00f3n cl\u00ednica del paciente. Valorar la relaci\u00f3n beneficio\/riesgo.<br \/>\n&#8211; Iniciar el tratamiento lo antes posible, realizando un seguimiento de la respuesta al mismo.<br \/>\n&#8211; Utilizar pautas de administraci\u00f3n sencillas, eligiendo la v\u00eda de administraci\u00f3n m\u00e1s adecuada (oral si es posible).<br \/>\n&#8211; Restringir en lo posible el n\u00famero de f\u00e1rmacos, evitando mantener medicamentos innecesarios hasta el \u00faltimo momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Farmacoterapia Paliativa. Administraci\u00f3n de Medicamentos La Sociedad Vasca de Cuidados Paliativos ha publicado este art\u00edculo sobre farmacoterapia paliativa. Una de las bases sobre la que se sustentan los cuidados paliativos es el control de los s\u00edntomas, que pueden ser m\u00faltiples, cambiantes, de intensidad variable y origen multifactorial. Para una adecuada farmacoterapia ser\u00e1 necesario: &#8211; Realizar [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[117,1026,586,145,22],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/17893"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/comments?post=17893"}],"version-history":[{"count":0,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/17893\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/media?parent=17893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/categories?post=17893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/tags?post=17893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}