{"id":21403,"date":"2012-04-20T13:16:41","date_gmt":"2012-04-20T17:16:41","guid":{"rendered":"http:\/\/blogviejo.sld.cu\/marionod\/?p=21403"},"modified":"2012-04-20T13:16:41","modified_gmt":"2012-04-20T17:16:41","slug":"okechukwu-felix-erondu-medical-imaging-intech-december-2011","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/marionod\/2012\/04\/20\/okechukwu-felix-erondu-medical-imaging-intech-december-2011\/","title":{"rendered":"Okechukwu Felix Erondu. Medical Imaging. InTech, December, 2011"},"content":{"rendered":"<p><a href=\"http:\/\/www.intechopen.com\/books\/medical-imaging\" target=\"_blank\">Okechukwu Felix Erondu. Medical Imaging. InTech, December, 2011<\/a><\/p>\n<p>Libro a texto completo de la editorial InTech. Lo que sabemos sobre y como hacer con la imaginolog\u00eda m\u00e9dica ha cambiado r\u00e1pidamente durante la \u00faltima d\u00e9cada, empezando por lo b\u00e1sico, siguiendo con los avances, y de pasar a lo abstracto. Este libro demuestra el horizonte m\u00e1s amplio que se ha convertido en el pilar de las ciencias m\u00e9dicas de la imagen, captura el concepto de diagn\u00f3stico m\u00e9dico, la gesti\u00f3n de la informaci\u00f3n digital y la investigaci\u00f3n. Se trata de una herramienta de valor incalculable para los radi\u00f3logos y especialistas en imagen, f\u00edsicos e investigadores interesados \u200b\u200ben diversos aspectos de la imagen. Idioma: ingl\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Okechukwu Felix Erondu. Medical Imaging. InTech, December, 2011 Libro a texto completo de la editorial InTech. Lo que sabemos sobre y como hacer con la imaginolog\u00eda m\u00e9dica ha cambiado r\u00e1pidamente durante la \u00faltima d\u00e9cada, empezando por lo b\u00e1sico, siguiendo con los avances, y de pasar a lo abstracto. Este libro demuestra el horizonte m\u00e1s amplio [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,254,11,111],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/21403"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/comments?post=21403"}],"version-history":[{"count":0,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/21403\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/media?parent=21403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/categories?post=21403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/tags?post=21403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}