{"id":36475,"date":"2016-11-17T00:54:28","date_gmt":"2016-11-17T04:54:28","guid":{"rendered":"http:\/\/blogs.sld.cu\/marionod\/?p=36475"},"modified":"2016-11-17T00:54:28","modified_gmt":"2016-11-17T04:54:28","slug":"genes-and-diseases","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/marionod\/2016\/11\/17\/genes-and-diseases\/","title":{"rendered":"Genes and Diseases"},"content":{"rendered":"<p><a href=\"www.sciencedirect.com\/science\/journal\/23523042\" target=\"_blank\">Genes and Diseases<\/a><\/p>\n<p>Revista internacional a texto completo y arbitrada de la editorial Elsevier para la medicina molecular y translacional. La revista se enfoca primariamente sobre la publicaci\u00f3n de investigaciones sobre las bases de moleculares y experimentales de la terap\u00e9utica de las enfermedades humanas. Los formatos de publicaci\u00f3n incluyen los art\u00edculos de investigaci\u00f3n completos, articulos de revision, comunicaciones cortas, correspondencia, comentario, visiones sobre noticias y observacion de investigaciones. Su enfasis estar\u00e1 ubicado sobre hipotesis, estudios mecan\u00edsticos relevantes a la patog\u00e9nesis y\/o terap\u00e9utica experimental de las enfermedades humanas<strong><em>.<\/em><\/strong> La revista tiene una autoria a nivel mundial y un amplio alcance en la investigaci\u00f3n biom\u00e9dica b\u00e1sica y \u00a0translacional de la biolog\u00eda molecular, gen\u00e9tica molecular y biolog\u00eda celular, incluyendo pero no limitado a proliferaci\u00f3n celular y apoptosis, transducci\u00f3n de se\u00f1al y biolog\u00eda de celulas madres. Idioma: ingl\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Genes and Diseases Revista internacional a texto completo y arbitrada de la editorial Elsevier para la medicina molecular y translacional. La revista se enfoca primariamente sobre la publicaci\u00f3n de investigaciones sobre las bases de moleculares y experimentales de la terap\u00e9utica de las enfermedades humanas. Los formatos de publicaci\u00f3n incluyen los art\u00edculos de investigaci\u00f3n completos, articulos [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[65,284,1774,9],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/36475"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/comments?post=36475"}],"version-history":[{"count":1,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/36475\/revisions"}],"predecessor-version":[{"id":36476,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/36475\/revisions\/36476"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/media?parent=36475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/categories?post=36475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/tags?post=36475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}