{"id":37975,"date":"2017-07-18T18:11:53","date_gmt":"2017-07-18T22:11:53","guid":{"rendered":"http:\/\/blogs.sld.cu\/marionod\/?p=37975"},"modified":"2017-07-18T18:11:53","modified_gmt":"2017-07-18T22:11:53","slug":"asianpacific-island-nursing-journal","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/marionod\/2017\/07\/18\/asianpacific-island-nursing-journal\/","title":{"rendered":"Asian\/Pacific Island Nursing Journal"},"content":{"rendered":"<p class=\"inherit-title\"><a href=\"http:\/\/digitalscholarship.unlv.edu\/apin\/\" target=\"_blank\">Asian\/Pacific Island Nursing Journal<\/a><\/p>\n<p class=\"inherit-title\">Revista a texto completo y arbitrada de frecuencia trimestral que suministra un f<span id=\"result_box\" class=\"\" lang=\"es\">oro para el intercambio de conocimientos en relaci\u00f3n con la salud de los asi\u00e1ticos y las islas del Pac\u00edfico y la atenci\u00f3n de enfermer\u00eda. Servir\u00e1 como una voz para la enfermer\u00eda y otros proveedores de atenci\u00f3n m\u00e9dica para la investigaci\u00f3n, la educaci\u00f3n y la pr\u00e1ctica. <span class=\"\">El alcance incluir\u00eda art\u00edculos referidos sobre investigaci\u00f3n, revisiones te\u00f3ricas, pr\u00e1cticas y temas de pol\u00edtica relacionados con la salud de la API.<\/span><\/span><\/p>\n<p>El alcance de la revista incluye, pero no se limita a:<br \/>\n-M\u00e9todos, intervenciones, instrumentaci\u00f3n y t\u00e9cnicas educativas propias de este grupo.<br \/>\n-Fundamentos te\u00f3ricos que aumentan la comprensi\u00f3n de la respuesta \u00fanica a los cambios en la salud y la enfermedad.<br \/>\n-Impactos bio psicosociales, espirituales y ecol\u00f3gicos en la pr\u00e1ctica, la educaci\u00f3n y la investigaci\u00f3n.<br \/>\n-Cuestiones pol\u00edticas como resultado de investigaciones rigurosas.<\/p>\n<p class=\"inherit-title\">Idioma: ingl\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asian\/Pacific Island Nursing Journal Revista a texto completo y arbitrada de frecuencia trimestral que suministra un foro para el intercambio de conocimientos en relaci\u00f3n con la salud de los asi\u00e1ticos y las islas del Pac\u00edfico y la atenci\u00f3n de enfermer\u00eda. Servir\u00e1 como una voz para la enfermer\u00eda y otros proveedores de atenci\u00f3n m\u00e9dica para la [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51,9],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/37975"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/comments?post=37975"}],"version-history":[{"count":1,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/37975\/revisions"}],"predecessor-version":[{"id":37976,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/37975\/revisions\/37976"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/media?parent=37975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/categories?post=37975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/tags?post=37975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}