{"id":38521,"date":"2017-11-28T18:44:04","date_gmt":"2017-11-28T22:44:04","guid":{"rendered":"http:\/\/blogs.sld.cu\/marionod\/?p=38521"},"modified":"2017-11-28T18:44:04","modified_gmt":"2017-11-28T22:44:04","slug":"journal-health-npeps","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/marionod\/2017\/11\/28\/journal-health-npeps\/","title":{"rendered":"Journal Health NPEPS"},"content":{"rendered":"<p><a href=\"https:\/\/periodicos.unemat.br\/index.php\/jhnpeps\/index\" target=\"_blank\">Journal Health NPEPS<\/a><\/p>\n<p>Revista a texto completo y arbitrada qie es una publicaci\u00f3n cient\u00edfica semestral idealizada a partir de 2015 por el Grupo de Investigaci\u00f3n NPEPS &#8211; Universidad del Estado de Mato Grosso (UNEMAT) para fomentar la discusi\u00f3n multidisciplinar de temas relacionados con las Ciencias de la Salud y Enfermer\u00eda con la originalidad, convirtiendo a la formaci\u00f3n acad\u00e9mica y la mejora continua de los profesionales de la salud, investigadores, gestores y comunidad. Idioma: portugu\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Journal Health NPEPS Revista a texto completo y arbitrada qie es una publicaci\u00f3n cient\u00edfica semestral idealizada a partir de 2015 por el Grupo de Investigaci\u00f3n NPEPS &#8211; Universidad del Estado de Mato Grosso (UNEMAT) para fomentar la discusi\u00f3n multidisciplinar de temas relacionados con las Ciencias de la Salud y Enfermer\u00eda con la originalidad, convirtiendo a [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51,112,9],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/38521"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/comments?post=38521"}],"version-history":[{"count":1,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/38521\/revisions"}],"predecessor-version":[{"id":38522,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/38521\/revisions\/38522"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/media?parent=38521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/categories?post=38521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/tags?post=38521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}