{"id":42017,"date":"2020-01-31T10:01:04","date_gmt":"2020-01-31T14:01:04","guid":{"rendered":"http:\/\/blogs.sld.cu\/marionod\/?p=42017"},"modified":"2020-01-31T10:01:04","modified_gmt":"2020-01-31T14:01:04","slug":"nucleus","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/marionod\/2020\/01\/31\/nucleus\/","title":{"rendered":"Nucleus"},"content":{"rendered":"<p><a href=\"http:\/\/nucleus.cubaenergia.cu\/index.php\/nucleus\" target=\"_blank\">Nucleus<\/a><\/p>\n<p>Revista a texto completo y arbitrada que es una publicaci\u00f3n cient\u00edfica semestral de perfil nuclear de la Agencia de Energ\u00eda Nuclear y Tecnolog\u00edas de Avanzada (AENTA), editada por el Centro de Gesti\u00f3n de la Informaci\u00f3n y Desarrollo de la Energ\u00eda (CUBAENERGIA).<br \/>\nSu prop\u00f3sito es validar el conocimiento cient\u00edfico de los especialistas nucleares y divulgar los principales resultados del programa nuclear cubano con fines pac\u00edficos. La revista publica art\u00edculos de autores cubanos y extranjeros en espa\u00f1ol e ingl\u00e9s en las tem\u00e1ticas de medicina nuclear, radiobiolog\u00eda, f\u00edsica nuclear, electr\u00f3nica nuclear, radioqu\u00edmica, gesti\u00f3n de desechos radiactivos, protecci\u00f3n radiol\u00f3gica y seguridad nuclear, y salvaguardias y no proliferaci\u00f3n, radioqu\u00edmica y aplicaciones nucleares en la salud humana, en la industria, en la agricultura, en el medio ambiente, entre otros campos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nucleus Revista a texto completo y arbitrada que es una publicaci\u00f3n cient\u00edfica semestral de perfil nuclear de la Agencia de Energ\u00eda Nuclear y Tecnolog\u00edas de Avanzada (AENTA), editada por el Centro de Gesti\u00f3n de la Informaci\u00f3n y Desarrollo de la Energ\u00eda (CUBAENERGIA). Su prop\u00f3sito es validar el conocimiento cient\u00edfico de los especialistas nucleares y divulgar [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[68,70,867,9],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/42017"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/comments?post=42017"}],"version-history":[{"count":1,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/42017\/revisions"}],"predecessor-version":[{"id":42018,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/posts\/42017\/revisions\/42018"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/media?parent=42017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/categories?post=42017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/marionod\/wp-json\/wp\/v2\/tags?post=42017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}