{"id":6139,"date":"2025-12-26T19:35:23","date_gmt":"2025-12-26T19:35:23","guid":{"rendered":"https:\/\/blogs.sld.cu\/oserranob\/?p=6139"},"modified":"2025-12-26T19:35:36","modified_gmt":"2025-12-26T19:35:36","slug":"disponible-nuevo-numero-de-database-nar","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/oserranob\/2025\/12\/26\/disponible-nuevo-numero-de-database-nar\/","title":{"rendered":"Disponible nuevo n\u00famero de Database-NAR"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.sld.cu\/oserranob\/files\/2025\/12\/NAR_DB.png\"><img loading=\"lazy\" class=\"alignleft wp-image-6140 size-full\" title=\"(c) Oxford University Press\" src=\"https:\/\/blogs.sld.cu\/oserranob\/files\/2025\/12\/NAR_DB.png\" alt=\"\" width=\"150\" height=\"85\" \/><\/a>84 nuevas bases de datos y 86 actualizaciones son presentadas en el n\u00famero Database de enero 2026, de la revista <em>Nucleic Acids Research<\/em>, que cubre genes, transcriptomas, enzimas, otras prote\u00ednas y haplotipos. Puede acceder a la descripci\u00f3n de esta edici\u00f3n en Rigden DJ, Fern\u00e1ndez XM. <a href=\"https:\/\/academic.oup.com\/nar\/advance-article\/doi\/10.1093\/nar\/gkaf1427\/8402365?searchresult=1\">The 2026 Nucleic Acids Research database issue and the online molecular biology database collection<\/a>. Nucleic Acids Research, 2025;gkaf1427, https:\/\/doi.org\/10.1093\/nar\/gkaf1427<\/p>\n","protected":false},"excerpt":{"rendered":"<p>84 nuevas bases de datos y 86 actualizaciones son presentadas en el n\u00famero Database de enero 2026, de la revista Nucleic Acids Research, que cubre genes, transcriptomas, enzimas, otras prote\u00ednas y haplotipos. Puede acceder a la descripci\u00f3n de esta edici\u00f3n en Rigden DJ, Fern\u00e1ndez XM. The 2026 Nucleic Acids Research database issue and the online [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,31],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/posts\/6139"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/comments?post=6139"}],"version-history":[{"count":3,"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/posts\/6139\/revisions"}],"predecessor-version":[{"id":6146,"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/posts\/6139\/revisions\/6146"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/media?parent=6139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/categories?post=6139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/oserranob\/wp-json\/wp\/v2\/tags?post=6139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}