{"id":33,"date":"2008-11-30T08:35:36","date_gmt":"2008-11-30T12:35:36","guid":{"rendered":"http:\/\/blogviejo.sld.cu\/stgomles\/2008\/11\/30\/zirconio-otra-alternativa-posible\/"},"modified":"2008-11-30T08:35:36","modified_gmt":"2008-11-30T12:35:36","slug":"zirconio-otra-alternativa-posible","status":"publish","type":"post","link":"https:\/\/blogs.sld.cu\/stgomles\/2008\/11\/30\/zirconio-otra-alternativa-posible\/","title":{"rendered":"Zirconio, otra alternativa posible"},"content":{"rendered":"<p><a href=\"http:\/\/www.aproden.com.ar\/pdf\/Articulo02.pdf\" target=\"_blank\">Zirconio, otra alternativa posible.<\/a><\/p>\n<p>Hoy en d\u00eda tanto las tecnolog\u00edas como los materiales dentales evolucionan a marchas aceleradas, y quiz\u00e1s esos nuevos materiales y las nuevas tecnolog\u00edas nos lleven cada vez m\u00e1s a pensar que uno de los objetivos de estos adelantos es trabajar con materiales alternativos a las aleaciones dentales. En este momento disponemos en el mercado de productos novedosos, como puede ser el \u00d3xido de Zirconio para la fabricaci\u00f3n de puentes cer\u00e1micos posteriores y tambi\u00e9n anteriores, \u00bfpor qu\u00e9 no?. <a title=\"Editar &quot;icon_pdf.gif&quot;\" href=\"http:\/\/blogviejo.sld.cu\/stgomles\/wp-admin\/media.php?action=edit&amp;attachment_id=10\"><img loading=\"lazy\" class=\"attachment-80x60\" src=\"http:\/\/blogs.sld.cu\/stgomles\/files\/2008\/11\/icon_pdf.gif\" alt=\"\" width=\"23\" height=\"9\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zirconio, otra alternativa posible. Hoy en d\u00eda tanto las tecnolog\u00edas como los materiales dentales evolucionan a marchas aceleradas, y quiz\u00e1s esos nuevos materiales y las nuevas tecnolog\u00edas nos lleven cada vez m\u00e1s a pensar que uno de los objetivos de estos adelantos es trabajar con materiales alternativos a las aleaciones dentales. En este momento disponemos [&hellip;]<\/p>\n","protected":false},"author":155,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/posts\/33"}],"collection":[{"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/users\/155"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":0,"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sld.cu\/stgomles\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}